{"id":8320,"date":"2023-04-06T09:25:38","date_gmt":"2023-04-06T09:25:38","guid":{"rendered":"https:\/\/merinox.nl\/?page_id=8320"},"modified":"2023-04-06T09:27:06","modified_gmt":"2023-04-06T09:27:06","slug":"tubo-in-rotolo","status":"publish","type":"page","link":"https:\/\/merinox.nl\/it\/tubo-in-rotolo\/","title":{"rendered":"Tubo in rotolo"},"content":{"rendered":"<div class=\"grizzly\">\n<div class=\"griz-usp\">\n<ul>\n<li><span class=\"vink\">\u2713<\/span>Disponibile a magazzino<\/li>\n<li><span class=\"vink\">\u2713<\/span>Dimensioni difficili<\/li>\n<li><span class=\"vink\">\u2713<\/span>Leghe speciali<\/li>\n<\/ul>\n<\/div>\n<h1>Tubo in rotolo<\/h1>\n<div class=\"section-intro\">\n<div class=\"section-intro-left\">\n<p>Nel nostro magazzino troverai il tubo in rotolo adatto a ogni tipo di applicazione e ai pi&ugrave; svariati contesti, destinato sia all&#8217;uso industriale che domestico. I nostri prodotti resistono alle deformazioni e alla corrosione e, grazie alla lunga esperienza maturata nel settore, offriamo servizi rispondenti a ogni genere di richiesta.<\/p>\n<div class=\"griz-cta\">\n<h4>Interessati al Tubo in rotolo?<\/h4>\n<p class=\"btn\"><a class=\"btn-quote\" href=\"mailto:info@merinox.nl\">contattateci<\/a><\/p>\n<\/div>\n<\/div>\n<div class=\"griz-img\"><img decoding=\"async\" src=\"http:\/\/merinox.nl\/wp-content\/uploads\/2020\/04\/Merinox_Alblasserdam_052.jpg\" alt=\"Tubo in rotolo\" \/><\/div>\n<\/div>\n<div class=\"section-2\">\n<h2>Acquista il tubo in rotolo dal nostro magazzino<\/h2>\n<div class=\"section-2-structure\">\n<div class=\"griz-img\"><img decoding=\"async\" src=\"http:\/\/merinox.nl\/wp-content\/uploads\/2020\/02\/Merinox_Alblasserdam_080-scaled.jpg\" alt=\"Tubo in rotolo\" \/><\/div>\n<div>\n<p>Tra le varie proposte in <a href=\"https:\/\/merinox.nl\/it\/\">catalogo dei tubi senza saldatura<\/a> sono presenti anche i tubi in rotolo, disponibili sia in rame nudo che in polietilene. Si tratta di prodotti assai versatili, impiegati in industria, idraulica e irrigazione. Ogni tubo in rotolo in vendita &egrave; munito di relativa certificazione e adatto ai condotti di fluidi in <a href=\"https:\/\/merinox.nl\/it\/tubo-senza-saldatura-alta-pressione\/\">alta pressione<\/a> indicati nella circolare del Ministero della Sanit&agrave; n.102\/1978. Il formato utilizzato per la vendita &egrave; il metro lineare.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"section-3\">\n<h2>Contattaci per informazioni<\/h2>\n<p>All&#8217;interno del nostro e-commerce troverai un&#8217;ampia gamma di prodotti, tra articoli per l&#8217;industria come <a href=\"https:\/\/merinox.nl\/it\/tubi-per-cromatografia\/\">i tubi per la cromatografia<\/a> e per uso privato. Il nostro magazzino <a href=\"https:\/\/merinox.nl\/it\/tubi-strumentali-rigidi\/\">dei tubi strumentali<\/a> &egrave; in costante aggiornamento e ogni articolo &egrave; acquistabile comodamente da casa. Assicuriamo a tutti i nostri clienti elevati standard di sicurezza e di affidabilit&agrave;, valori che da sempre contraddistinguono il nostro operato. Non esitare a contattarci via <a href=\"mailto:sales@merinox.nl\">sales@merinox.nl<\/a> in caso di dubbi o richieste specifiche sui nostro tubo in rotolo o <a href=\"https:\/\/merinox.nl\/it\/tubi-in-lega-di-nichel\/\">tubo in lega di nichel<\/a> o titanio.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u2713Disponibile a magazzino \u2713Dimensioni difficili \u2713Leghe speciali Tubo in rotolo Nel nostro magazzino troverai il tubo in rotolo adatto a ogni tipo di applicazione e ai pi&ugrave; svariati contesti, destinato sia all&#8217;uso industriale che domestico. I nostri prodotti resistono alle deformazioni e alla corrosione e, grazie alla lunga esperienza maturata nel settore, offriamo servizi rispondenti [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8320","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Proponiamo tutti i tipi di tubo in rotolo in ogni dimensione, specifici per l&#039;industria, per gli impianti idrotermosanitari e per l&#039;irrigazione. Offriamo tubi in rotolo di ogni spessore e diametro, adatti alle pi\u00f9 svariate esigenze.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"tpkDKAGj3NsVeSOmXoBUq-Ap331QYdlsP7B9SpI43AQ\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/merinox.nl\/it\/tubo-in-rotolo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Merinox -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Tubi in rotoli in ogni demensione per l\u2019industria - Merinox\" \/>\n\t\t<meta property=\"og:description\" content=\"Proponiamo tutti i tipi di tubo in rotolo in ogni dimensione, specifici per l&#039;industria, per gli impianti idrotermosanitari e per l&#039;irrigazione. Offriamo tubi in rotolo di ogni spessore e diametro, adatti alle pi\u00f9 svariate esigenze.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/merinox.nl\/it\/tubo-in-rotolo\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-04-06T09:25:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-04-06T09:27:06+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Tubi in rotoli in ogni demensione per l\u2019industria - Merinox\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Proponiamo tutti i tipi di tubo in rotolo in ogni dimensione, specifici per l&#039;industria, per gli impianti idrotermosanitari e per l&#039;irrigazione. Offriamo tubi in rotolo di ogni spessore e diametro, adatti alle pi\u00f9 svariate esigenze.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/merinox.nl\\\/it\\\/tubo-in-rotolo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/merinox.nl\\\/it\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/merinox.nl\\\/it\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/merinox.nl\\\/it\\\/tubo-in-rotolo\\\/#listItem\",\"name\":\"Tubo in rotolo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/merinox.nl\\\/it\\\/tubo-in-rotolo\\\/#listItem\",\"position\":2,\"name\":\"Tubo in rotolo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/merinox.nl\\\/it\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/merinox.nl\\\/it\\\/#organization\",\"name\":\"Merinox\",\"url\":\"https:\\\/\\\/merinox.nl\\\/it\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/merinox.nl\\\/it\\\/tubo-in-rotolo\\\/#webpage\",\"url\":\"https:\\\/\\\/merinox.nl\\\/it\\\/tubo-in-rotolo\\\/\",\"name\":\"Tubi in rotoli in ogni demensione per l\\u2019industria - Merinox\",\"description\":\"Proponiamo tutti i tipi di tubo in rotolo in ogni dimensione, specifici per l'industria, per gli impianti idrotermosanitari e per l'irrigazione. Offriamo tubi in rotolo di ogni spessore e diametro, adatti alle pi\\u00f9 svariate esigenze.\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/merinox.nl\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/merinox.nl\\\/it\\\/tubo-in-rotolo\\\/#breadcrumblist\"},\"datePublished\":\"2023-04-06T09:25:38+02:00\",\"dateModified\":\"2023-04-06T09:27:06+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/merinox.nl\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/merinox.nl\\\/it\\\/\",\"name\":\"Merinox\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/merinox.nl\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Tubi in rotoli in ogni demensione per l\u2019industria - Merinox","description":"Proponiamo tutti i tipi di tubo in rotolo in ogni dimensione, specifici per l'industria, per gli impianti idrotermosanitari e per l'irrigazione. Offriamo tubi in rotolo di ogni spessore e diametro, adatti alle pi\u00f9 svariate esigenze.","canonical_url":"https:\/\/merinox.nl\/it\/tubo-in-rotolo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"tpkDKAGj3NsVeSOmXoBUq-Ap331QYdlsP7B9SpI43AQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/merinox.nl\/it\/tubo-in-rotolo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/merinox.nl\/it\/#listItem","position":1,"name":"Home","item":"https:\/\/merinox.nl\/it\/","nextItem":{"@type":"ListItem","@id":"https:\/\/merinox.nl\/it\/tubo-in-rotolo\/#listItem","name":"Tubo in rotolo"}},{"@type":"ListItem","@id":"https:\/\/merinox.nl\/it\/tubo-in-rotolo\/#listItem","position":2,"name":"Tubo in rotolo","previousItem":{"@type":"ListItem","@id":"https:\/\/merinox.nl\/it\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/merinox.nl\/it\/#organization","name":"Merinox","url":"https:\/\/merinox.nl\/it\/"},{"@type":"WebPage","@id":"https:\/\/merinox.nl\/it\/tubo-in-rotolo\/#webpage","url":"https:\/\/merinox.nl\/it\/tubo-in-rotolo\/","name":"Tubi in rotoli in ogni demensione per l\u2019industria - Merinox","description":"Proponiamo tutti i tipi di tubo in rotolo in ogni dimensione, specifici per l'industria, per gli impianti idrotermosanitari e per l'irrigazione. Offriamo tubi in rotolo di ogni spessore e diametro, adatti alle pi\u00f9 svariate esigenze.","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/merinox.nl\/it\/#website"},"breadcrumb":{"@id":"https:\/\/merinox.nl\/it\/tubo-in-rotolo\/#breadcrumblist"},"datePublished":"2023-04-06T09:25:38+02:00","dateModified":"2023-04-06T09:27:06+02:00"},{"@type":"WebSite","@id":"https:\/\/merinox.nl\/it\/#website","url":"https:\/\/merinox.nl\/it\/","name":"Merinox","inLanguage":"it-IT","publisher":{"@id":"https:\/\/merinox.nl\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Merinox -","og:type":"article","og:title":"Tubi in rotoli in ogni demensione per l\u2019industria - Merinox","og:description":"Proponiamo tutti i tipi di tubo in rotolo in ogni dimensione, specifici per l'industria, per gli impianti idrotermosanitari e per l'irrigazione. Offriamo tubi in rotolo di ogni spessore e diametro, adatti alle pi\u00f9 svariate esigenze.","og:url":"https:\/\/merinox.nl\/it\/tubo-in-rotolo\/","article:published_time":"2023-04-06T09:25:38+00:00","article:modified_time":"2023-04-06T09:27:06+00:00","twitter:card":"summary","twitter:title":"Tubi in rotoli in ogni demensione per l\u2019industria - Merinox","twitter:description":"Proponiamo tutti i tipi di tubo in rotolo in ogni dimensione, specifici per l'industria, per gli impianti idrotermosanitari e per l'irrigazione. Offriamo tubi in rotolo di ogni spessore e diametro, adatti alle pi\u00f9 svariate esigenze."},"aioseo_meta_data":{"post_id":"8320","title":"Tubi in rotoli in ogni demensione per l\u2019industria #separator_sa #site_title","description":"Proponiamo tutti i tipi di tubo in rotolo in ogni dimensione, specifici per l'industria, per gli impianti idrotermosanitari e per l'irrigazione. Offriamo tubi in rotolo di ogni spessore e diametro, adatti alle pi\u00f9 svariate esigenze.","keywords":[],"keyphrases":{"focus":{"keyphrase":"Tubo in rotolo","score":90,"analysis":{"keyphraseInTitle":{"score":3,"maxScore":9,"error":1},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":3},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-04-06 09:25:38","updated":"2025-06-04 12:40:33","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/merinox.nl\/it\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTubo in rotolo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/merinox.nl\/it\/"},{"label":"Tubo in rotolo","link":"https:\/\/merinox.nl\/it\/tubo-in-rotolo\/"}],"_links":{"self":[{"href":"https:\/\/merinox.nl\/it\/wp-json\/wp\/v2\/pages\/8320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/merinox.nl\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/merinox.nl\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/merinox.nl\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/merinox.nl\/it\/wp-json\/wp\/v2\/comments?post=8320"}],"version-history":[{"count":2,"href":"https:\/\/merinox.nl\/it\/wp-json\/wp\/v2\/pages\/8320\/revisions"}],"predecessor-version":[{"id":8322,"href":"https:\/\/merinox.nl\/it\/wp-json\/wp\/v2\/pages\/8320\/revisions\/8322"}],"wp:attachment":[{"href":"https:\/\/merinox.nl\/it\/wp-json\/wp\/v2\/media?parent=8320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}